{"id":3223,"date":"2025-09-02T06:18:18","date_gmt":"2025-09-02T06:18:18","guid":{"rendered":"https:\/\/seeco.es\/?post_type=product&#038;p=3223"},"modified":"2026-04-16T09:51:34","modified_gmt":"2026-04-16T09:51:34","slug":"i-curso-de-ecografia-de-pene","status":"publish","type":"product","link":"https:\/\/seeco.es\/en\/curso-ecografia\/i-curso-de-ecografia-de-pene\/","title":{"rendered":"III Curso de Ecograf\u00eda de Pene"},"content":{"rendered":"<h2 style=\"text-align: left;\">III Curso de Ecograf\u00eda de Pene<\/h2>\n<p style=\"text-align: left;\"><span class=\"s1\"><b>MADRID, 10 y 11 de abril de 2026<\/b><\/span><\/p>\n<p style=\"text-align: left;\"><a href=\"https:\/\/seeco.es\/wp-content\/uploads\/2026\/02\/04-Pene26-1.pdf\" target=\"_blank\" rel=\"noopener\">Desc\u00e1rgate desde aqu\u00ed el programa<\/a><\/p>\n<p>Cuota de inscripci\u00f3n Curso Presencial: 998,25 \u20ac<\/p>\n<p><strong>Discount<\/strong> from 5% for SEECO partners.<br \/>\nRegistration includes attendance at sessions, coffee breaks and a working lunch.<br \/>\nTechnical Secretariat: <b>Spanish Society of Ultrasound<\/b><\/p>\n<ul>\n<li><b>Phone: <a href=\"tel:+34 655 694 698\">+34 655 694 698<\/a> <\/b><\/li>\n<li><b>E-mail: <\/b><a href=\"mailto:secretariatecnica@seeco.es\"><b>secretariatecnica@seeco.es<\/b><\/a><\/li>\n<\/ul>\n<p><strong>Note<\/strong><br \/>\nLa realizaci\u00f3n de este Curso queda supeditada a una demanda m\u00ednima de 15 asistentes. <strong>Plazas limitadas<\/strong>.<br \/>\nSe entregar\u00e1 certificado de asistencia al Curso avalado por S.E.ECO. (miembro de EFSUMB) de 12:30 horas de formaci\u00f3n te\u00f3rica.<\/p>","protected":false},"excerpt":{"rendered":"<p style=\"text-align: center;\">D\u00edas 10 y 11 de abril de 2026<br \/>\nMADRID<\/p>","protected":false},"featured_media":3918,"template":"","meta":[],"product_brand":[],"product_cat":[77],"product_tag":[76],"class_list":{"0":"post-3223","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-actividades-realizadas","7":"product_tag-curso-presencial","9":"first","10":"instock","11":"sold-individually","12":"taxable","13":"shipping-taxable","14":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>III Curso de Ecograf\u00eda de Pene<\/title>\n<meta name=\"description\" content=\"III Curso de Ecograf\u00eda de Pene organizado por SEECO (Sociedad Espa\u00f1ola de Ecograf\u00eda). Plazas limitadas. Se entregar\u00e1 certificado de asistencia al Curso avalado por S.E.ECO.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seeco.es\/en\/curso-ecografia\/i-curso-de-ecografia-de-pene\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"III Curso de Ecograf\u00eda de Pene\" \/>\n<meta property=\"og:description\" content=\"III Curso de Ecograf\u00eda de Pene organizado por SEECO (Sociedad Espa\u00f1ola de Ecograf\u00eda). Plazas limitadas. Se entregar\u00e1 certificado de asistencia al Curso avalado por S.E.ECO.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seeco.es\/en\/curso-ecografia\/i-curso-de-ecografia-de-pene\/\" \/>\n<meta property=\"og:site_name\" content=\"SEECO\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T09:51:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seeco.es\/wp-content\/uploads\/2026\/02\/04-Pene26-600x600-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seeco.es\\\/curso-ecografia\\\/i-curso-de-ecografia-de-pene\\\/\",\"url\":\"https:\\\/\\\/seeco.es\\\/curso-ecografia\\\/i-curso-de-ecografia-de-pene\\\/\",\"name\":\"III Curso de Ecograf\u00eda de Pene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seeco.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seeco.es\\\/curso-ecografia\\\/i-curso-de-ecografia-de-pene\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seeco.es\\\/curso-ecografia\\\/i-curso-de-ecografia-de-pene\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seeco.es\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/04-Pene26-600x600-1.jpg\",\"datePublished\":\"2025-09-02T06:18:18+00:00\",\"dateModified\":\"2026-04-16T09:51:34+00:00\",\"description\":\"III Curso de Ecograf\u00eda de Pene organizado por SEECO (Sociedad Espa\u00f1ola de Ecograf\u00eda). Plazas limitadas. Se entregar\u00e1 certificado de asistencia al Curso avalado por S.E.ECO.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seeco.es\\\/curso-ecografia\\\/i-curso-de-ecografia-de-pene\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seeco.es\\\/curso-ecografia\\\/i-curso-de-ecografia-de-pene\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/seeco.es\\\/curso-ecografia\\\/i-curso-de-ecografia-de-pene\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seeco.es\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/04-Pene26-600x600-1.jpg\",\"contentUrl\":\"https:\\\/\\\/seeco.es\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/04-Pene26-600x600-1.jpg\",\"width\":600,\"height\":600,\"caption\":\"Curso de Ecograf\u00eda de Pene\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seeco.es\\\/curso-ecografia\\\/i-curso-de-ecografia-de-pene\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/seeco.es\\\/seeco\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/seeco.es\\\/en\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"III Curso de Ecograf\u00eda de Pene\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seeco.es\\\/#website\",\"url\":\"https:\\\/\\\/seeco.es\\\/\",\"name\":\"SEECO\",\"description\":\"Sociedad Espa\u00f1ola de Ecograf\u00eda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seeco.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"III Curso de Ecograf\u00eda de Pene","description":"III Curso de Ecograf\u00eda de Pene organizado por SEECO (Sociedad Espa\u00f1ola de Ecograf\u00eda). Plazas limitadas. Se entregar\u00e1 certificado de asistencia al Curso avalado por S.E.ECO.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seeco.es\/en\/curso-ecografia\/i-curso-de-ecografia-de-pene\/","og_locale":"en_GB","og_type":"article","og_title":"III Curso de Ecograf\u00eda de Pene","og_description":"III Curso de Ecograf\u00eda de Pene organizado por SEECO (Sociedad Espa\u00f1ola de Ecograf\u00eda). Plazas limitadas. Se entregar\u00e1 certificado de asistencia al Curso avalado por S.E.ECO.","og_url":"https:\/\/seeco.es\/en\/curso-ecografia\/i-curso-de-ecografia-de-pene\/","og_site_name":"SEECO","article_modified_time":"2026-04-16T09:51:34+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/seeco.es\/wp-content\/uploads\/2026\/02\/04-Pene26-600x600-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seeco.es\/curso-ecografia\/i-curso-de-ecografia-de-pene\/","url":"https:\/\/seeco.es\/curso-ecografia\/i-curso-de-ecografia-de-pene\/","name":"III Curso de Ecograf\u00eda de Pene","isPartOf":{"@id":"https:\/\/seeco.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seeco.es\/curso-ecografia\/i-curso-de-ecografia-de-pene\/#primaryimage"},"image":{"@id":"https:\/\/seeco.es\/curso-ecografia\/i-curso-de-ecografia-de-pene\/#primaryimage"},"thumbnailUrl":"https:\/\/seeco.es\/wp-content\/uploads\/2026\/02\/04-Pene26-600x600-1.jpg","datePublished":"2025-09-02T06:18:18+00:00","dateModified":"2026-04-16T09:51:34+00:00","description":"III Curso de Ecograf\u00eda de Pene organizado por SEECO (Sociedad Espa\u00f1ola de Ecograf\u00eda). Plazas limitadas. Se entregar\u00e1 certificado de asistencia al Curso avalado por S.E.ECO.","breadcrumb":{"@id":"https:\/\/seeco.es\/curso-ecografia\/i-curso-de-ecografia-de-pene\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seeco.es\/curso-ecografia\/i-curso-de-ecografia-de-pene\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/seeco.es\/curso-ecografia\/i-curso-de-ecografia-de-pene\/#primaryimage","url":"https:\/\/seeco.es\/wp-content\/uploads\/2026\/02\/04-Pene26-600x600-1.jpg","contentUrl":"https:\/\/seeco.es\/wp-content\/uploads\/2026\/02\/04-Pene26-600x600-1.jpg","width":600,"height":600,"caption":"Curso de Ecograf\u00eda de Pene"},{"@type":"BreadcrumbList","@id":"https:\/\/seeco.es\/curso-ecografia\/i-curso-de-ecografia-de-pene\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/seeco.es\/seeco\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/seeco.es\/en\/tienda\/"},{"@type":"ListItem","position":3,"name":"III Curso de Ecograf\u00eda de Pene"}]},{"@type":"WebSite","@id":"https:\/\/seeco.es\/#website","url":"https:\/\/seeco.es\/","name":"SEECO","description":"Spanish Society of Ultrasound","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seeco.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/seeco.es\/en\/wp-json\/wp\/v2\/product\/3223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seeco.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/seeco.es\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seeco.es\/en\/wp-json\/wp\/v2\/media\/3918"}],"wp:attachment":[{"href":"https:\/\/seeco.es\/en\/wp-json\/wp\/v2\/media?parent=3223"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/seeco.es\/en\/wp-json\/wp\/v2\/product_brand?post=3223"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/seeco.es\/en\/wp-json\/wp\/v2\/product_cat?post=3223"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/seeco.es\/en\/wp-json\/wp\/v2\/product_tag?post=3223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}